{"id":92516,"date":"2020-11-20T19:32:52","date_gmt":"2020-11-20T18:32:52","guid":{"rendered":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg"},"modified":"2020-11-20T19:33:05","modified_gmt":"2020-11-20T18:33:05","slug":"keplerstrasse-2","status":"inherit","type":"attachment","link":"https:\/\/kapitel-zwei.de\/it\/keplerstrasse-2\/","title":{"rendered":"Keplerstra\u00dfe"},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-92516","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v24.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Keplerstra\u00dfe - Kapitel Zwei Berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keplerstra\u00dfe - Kapitel Zwei Berlin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Kapitel Zwei Berlin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kapitelzwei\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-20T18:33:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kapitelzwei\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg\",\"url\":\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg\",\"name\":\"Keplerstra\u00dfe - Kapitel Zwei Berlin\",\"isPartOf\":{\"@id\":\"https:\/\/kapitel-zwei.de\/#website\"},\"datePublished\":\"2020-11-20T18:32:52+00:00\",\"dateModified\":\"2020-11-20T18:33:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/kapitel-zwei.de\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Keplerstra\u00dfe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kapitel-zwei.de\/#website\",\"url\":\"https:\/\/kapitel-zwei.de\/\",\"name\":\"Kapitel Zwei Berlin\",\"description\":\"Deutschkurs Berlin | Sprachschule Berlin | German language school Berlin | telc Berlin | Deutsch Pr\u00fcfung Berlin | Intensive German courses Berlin | TestDaF Pr\u00fcfung | Online Kurse\",\"publisher\":{\"@id\":\"https:\/\/kapitel-zwei.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kapitel-zwei.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kapitel-zwei.de\/#organization\",\"name\":\"Kapitel Zwei. Deutsch-Sprachschule Berlin GmbH\",\"url\":\"https:\/\/kapitel-zwei.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kapitel-zwei.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2018\/08\/Kapitel-Zwei-Berlin-Sprachschule-Deutsch-Deutschkurse-Berlin.jpg\",\"contentUrl\":\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2018\/08\/Kapitel-Zwei-Berlin-Sprachschule-Deutsch-Deutschkurse-Berlin.jpg\",\"width\":350,\"height\":101,\"caption\":\"Kapitel Zwei. Deutsch-Sprachschule Berlin GmbH\"},\"image\":{\"@id\":\"https:\/\/kapitel-zwei.de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kapitelzwei\/\",\"https:\/\/x.com\/kapitelzwei\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Keplerstra\u00dfe - Kapitel Zwei Berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg","og_locale":"it_IT","og_type":"article","og_title":"Keplerstra\u00dfe - Kapitel Zwei Berlin","og_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg","og_site_name":"Kapitel Zwei Berlin","article_publisher":"https:\/\/www.facebook.com\/kapitelzwei\/","article_modified_time":"2020-11-20T18:33:05+00:00","og_image":[{"width":531,"height":348,"url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@kapitelzwei","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg","url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg","name":"Keplerstra\u00dfe - Kapitel Zwei Berlin","isPartOf":{"@id":"https:\/\/kapitel-zwei.de\/#website"},"datePublished":"2020-11-20T18:32:52+00:00","dateModified":"2020-11-20T18:33:05+00:00","breadcrumb":{"@id":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kapitel-zwei.de\/it\/"},{"@type":"ListItem","position":2,"name":"Keplerstra\u00dfe"}]},{"@type":"WebSite","@id":"https:\/\/kapitel-zwei.de\/#website","url":"https:\/\/kapitel-zwei.de\/","name":"Kapitel Zwei Berlin","description":"Deutschkurs Berlin | Sprachschule Berlin | German language school Berlin | telc Berlin | Deutsch Pr\u00fcfung Berlin | Intensive German courses Berlin | TestDaF Pr\u00fcfung | Online Kurse","publisher":{"@id":"https:\/\/kapitel-zwei.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kapitel-zwei.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/kapitel-zwei.de\/#organization","name":"Kapitel Zwei. Deutsch-Sprachschule Berlin GmbH","url":"https:\/\/kapitel-zwei.de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kapitel-zwei.de\/#\/schema\/logo\/image\/","url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2018\/08\/Kapitel-Zwei-Berlin-Sprachschule-Deutsch-Deutschkurse-Berlin.jpg","contentUrl":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2018\/08\/Kapitel-Zwei-Berlin-Sprachschule-Deutsch-Deutschkurse-Berlin.jpg","width":350,"height":101,"caption":"Kapitel Zwei. Deutsch-Sprachschule Berlin GmbH"},"image":{"@id":"https:\/\/kapitel-zwei.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kapitelzwei\/","https:\/\/x.com\/kapitelzwei"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"197\" src=\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-300x197.jpg\" class=\"attachment-medium size-medium\" alt=\"Keplerstra\u00dfe\" srcset=\"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-300x197.jpg 300w, https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-80x52.jpg 80w, https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg 531w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Keplerstra\u00dfe","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":531,"height":348,"file":"2020\/11\/Keplerstrasse.jpg","sizes":{"medium":{"file":"Keplerstrasse-300x197.jpg","width":300,"height":197,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-300x197.jpg"},"thumbnail":{"file":"Keplerstrasse-80x52.jpg","width":80,"height":52,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-80x52.jpg"},"widget":{"file":"Keplerstrasse-36x36.jpg","width":36,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-36x36.jpg"},"square":{"file":"Keplerstrasse-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-180x180.jpg"},"portfolio":{"file":"Keplerstrasse-495x348.jpg","width":495,"height":348,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-495x348.jpg"},"portfolio_small":{"file":"Keplerstrasse-260x185.jpg","width":260,"height":185,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-260x185.jpg"},"entry_with_sidebar":{"file":"Keplerstrasse-531x321.jpg","width":531,"height":321,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse-531x321.jpg"},"full":{"file":"Keplerstrasse.jpg","width":531,"height":348,"mime_type":"image\/jpeg","source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/kapitel-zwei.de\/wp-content\/uploads\/2020\/11\/Keplerstrasse.jpg","_links":{"self":[{"href":"https:\/\/kapitel-zwei.de\/it\/wp-json\/wp\/v2\/media\/92516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kapitel-zwei.de\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/kapitel-zwei.de\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/kapitel-zwei.de\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/kapitel-zwei.de\/it\/wp-json\/wp\/v2\/comments?post=92516"}]}}